{"id":2116,"date":"2024-02-10T19:51:35","date_gmt":"2024-02-10T14:21:35","guid":{"rendered":"https:\/\/alarmlight.in\/?post_type=product&#038;p=2116"},"modified":"2024-02-10T19:52:02","modified_gmt":"2024-02-10T14:22:02","slug":"qap80bz","status":"publish","type":"product","link":"https:\/\/alarmlight.in\/index.php\/product\/qap80bz\/","title":{"rendered":"QAP80BZ"},"content":{"rendered":"<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">High Siren Buzzer, Wall Mount Type<br \/>\nMax.105dB<\/div>\n<div class=\"prod_icons\"><img decoding=\"async\" title=\"IP65\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/34.gif\" alt=\"IP65\" \/><img decoding=\"async\" title=\"-25\u2103 ~ +50\u2103\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/88.gif\" alt=\"-25\u2103 ~ +50\u2103\" \/><img decoding=\"async\" title=\"Buzzer\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/22.gif\" alt=\"Buzzer\" \/><img decoding=\"async\" title=\"105dB\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/73.gif\" alt=\"105dB\" \/><img decoding=\"async\" title=\"NPN-Transistor Type\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/63.gif\" alt=\"NPN-Transistor Type\" \/><img decoding=\"async\" title=\"RoHS\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/38.gif\" alt=\"RoHS\" \/><\/div>\n<\/div>\n<ul class=\"prod_info_sub\">\n<li>Product FeatureHigh Buzzer (Max. 105dB at 1m)<\/li>\n<li>VoltageDC:12V,24V<\/li>\n<li>DimensionDiameter : \u00d883mm\u00a0<b class=\"bar\">\u2502<\/b>Height : 129\u00a0<b class=\"bar\">\u2502<\/b>Depth : 93<\/li>\n<li>MaterialsABS<\/li>\n<li>Protection ratingIP65<\/li>\n<li class=\"cert\">Certificate<img decoding=\"async\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons\/02.gif\" \/><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">\n<div class=\"prod_box1\">\n<div class=\"prod_txt\">High Siren Buzzer, Wall Mount Type<br \/>\nMax.105dB<\/div>\n<div class=\"prod_icons\"><img decoding=\"async\" title=\"IP65\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/34.gif\" alt=\"IP65\" \/><img decoding=\"async\" title=\"-25\u2103 ~ +50\u2103\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/88.gif\" alt=\"-25\u2103 ~ +50\u2103\" \/><img decoding=\"async\" title=\"Buzzer\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/22.gif\" alt=\"Buzzer\" \/><img decoding=\"async\" title=\"105dB\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/73.gif\" alt=\"105dB\" \/><img decoding=\"async\" title=\"NPN-Transistor Type\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/63.gif\" alt=\"NPN-Transistor Type\" \/><img decoding=\"async\" title=\"RoHS\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons_new\/38.gif\" alt=\"RoHS\" \/><\/div>\n<\/div>\n<ul class=\"prod_info_sub\">\n<li>Product FeatureHigh Buzzer (Max. 105dB at 1m)<\/li>\n<li>VoltageDC:12V,24V<\/li>\n<li>DimensionDiameter : \u00d883mm\u00a0<b class=\"bar\">\u2502<\/b>Height : 129\u00a0<b class=\"bar\">\u2502<\/b>Depth : 93<\/li>\n<li>MaterialsABS<\/li>\n<li>Protection ratingIP65<\/li>\n<li class=\"cert\">Certificate<img decoding=\"async\" src=\"https:\/\/www.qlight.com\/productdata\/properties\/icons\/02.gif\" \/><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":2114,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[40,52,39],"product_tag":[],"_links":{"self":[{"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product\/2116"}],"collection":[{"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product\/2116\/revisions"}],"predecessor-version":[{"id":2117,"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product\/2116\/revisions\/2117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/media?parent=2116"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product_cat?post=2116"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/alarmlight.in\/index.php\/wp-json\/wp\/v2\/product_tag?post=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}